{"id":3073,"date":"2019-01-01T10:02:53","date_gmt":"2019-01-01T09:02:53","guid":{"rendered":"https:\/\/www.ff-reichertshausen.de\/cms\/?page_id=3073"},"modified":"2021-02-21T21:53:33","modified_gmt":"2021-02-21T20:53:33","slug":"einsaetze-2020","status":"publish","type":"page","link":"https:\/\/www.ff-reichertshausen.de\/cms\/einsaetze\/einsaetze-2021\/einsaetze-2020\/","title":{"rendered":"Eins\u00e4tze 2020"},"content":{"rendered":"<p><strong>Unser Einsatz <\/strong>war zuletzt notwendig:<\/p>\n<table width=\"380\">\n<tbody>\n<tr>\n<th style=\"text-align: center;\"><strong>Nr<\/strong><\/th>\n<th style=\"text-align: center;\"><strong>Datum<\/strong><\/th>\n<th style=\"text-align: center;\">Uhrzeit<\/th>\n<th>Ort und Einsatz<\/th>\n<th style=\"text-align: center;\">Dauer<br>(Std.)<\/th>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">32<\/td>\n<td style=\"text-align: center;\">14.12.2020<\/td>\n<td style=\"text-align: center;\">7:16<\/td>\n<td>Paindorf<br>PKW-Brand<\/td>\n<td style=\"text-align: center;\">3,00<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">31<\/td>\n<td style=\"text-align: center;\">07.11.2020<\/td>\n<td style=\"text-align: center;\">2:07<\/td>\n<td>Letten<br>Dachstuhlbrand &#8211; Fehlalarm<\/td>\n<td style=\"text-align: center;\">0,25<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">30<\/td>\n<td style=\"text-align: center;\">29.10.2020<\/td>\n<td style=\"text-align: center;\">17:57<\/td>\n<td>Kreut<br>Verkehrsunfall &#8211; Fehlalarm<br>(Meldung \u00fcber e-call)<\/td>\n<td style=\"text-align: center;\">0,5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">29<\/td>\n<td style=\"text-align: center;\">20.09.2020<\/td>\n<td style=\"text-align: center;\">20:57<\/td>\n<td>B13 H\u00f6he Salmading<br>Verkehrsunfall<\/td>\n<td style=\"text-align: center;\">1,5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">28<\/td>\n<td style=\"text-align: center;\">12.07.2020<\/td>\n<td style=\"text-align: center;\">15:25<\/td>\n<td>Grafing<br>Brand im Freien &#8211; Nachschau<\/td>\n<td style=\"text-align: center;\">0,75<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">27<\/td>\n<td style=\"text-align: center;\">05.07.2020<\/td>\n<td style=\"text-align: center;\">10:40<\/td>\n<td>Oberpaindorf<br>Person von Zug erfasst<\/td>\n<td style=\"text-align: center;\">3,0<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">26<\/td>\n<td style=\"text-align: center;\">29.06.2020<\/td>\n<td style=\"text-align: center;\">14:05<\/td>\n<td>Ilmm\u00fcnster &#8211; Paunzhausen<br>Verkehrsunfall<\/td>\n<td style=\"text-align: center;\">0,5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">25<\/td>\n<td style=\"text-align: center;\">08.06.2020<\/td>\n<td style=\"text-align: center;\">15:45<\/td>\n<td>Pfaffenhofen &#8211; Reichertshausen<br>Zufuhr Schutzmaterial<br>*** Katastrophenschutzeinsatz ***<\/td>\n<td style=\"text-align: center;\">0,75<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">24<\/td>\n<td style=\"text-align: center;\">02.05.2020<\/td>\n<td style=\"text-align: center;\">13:38<\/td>\n<td>Oberwohlbach<br>Brand Lagerhalle<\/td>\n<td style=\"text-align: center;\">2,0<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">23<\/td>\n<td style=\"text-align: center;\">22.04.2020<\/td>\n<td style=\"text-align: center;\">18:04<\/td>\n<td>Pischelsdorf<br>Kornackerstra\u00dfe<br>Kellerbrand<\/td>\n<td style=\"text-align: center;\">0,25<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">22<\/td>\n<td style=\"text-align: center;\">10.04.2020<\/td>\n<td style=\"text-align: center;\">12:18<\/td>\n<td>Reichertshausen &#8211; Kreut<br>Verkehrsunfall<br>PKW von Stra\u00dfe <br>abgekommen<\/td>\n<td style=\"text-align: center;\">1,66<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">21<\/td>\n<td style=\"text-align: center;\">16.03.2020<\/td>\n<td style=\"text-align: center;\">14:25<\/td>\n<td>Kreut<br>\u00d6lspur<\/td>\n<td style=\"text-align: center;\">0,66<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">20<\/td>\n<td style=\"text-align: center;\">06.03.2020<\/td>\n<td style=\"text-align: center;\">17:15<\/td>\n<td>Reichertshausen<br>Absicherung<br>Maibaum umlegen<\/td>\n<td style=\"text-align: center;\">1,5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">19<\/td>\n<td style=\"text-align: center;\">23.02.2020<\/td>\n<td style=\"text-align: center;\">13:00<\/td>\n<td>Begleitung<br>Faschingszug<\/td>\n<td style=\"text-align: center;\">4,0<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">18<\/td>\n<td style=\"text-align: center;\">23.02.2020<\/td>\n<td style=\"text-align: center;\">13:00<\/td>\n<td>Reichertshausen<br>Faschingszug<br>Stra\u00dfensicherung<\/td>\n<td style=\"text-align: center;\">0,75<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">17<\/td>\n<td style=\"text-align: center;\">13.02.2020<\/td>\n<td style=\"text-align: center;\">3:46<\/td>\n<td>Reichertshausen<br>First Responder<\/td>\n<td style=\"text-align: center;\">1,0<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">16<\/td>\n<td style=\"text-align: center;\">10.02.2020<\/td>\n<td style=\"text-align: center;\">12:49<\/td>\n<td>Reichertshausen<br>Pfaffenhofener Stra\u00dfe<br>Dach abgedeckt<\/td>\n<td style=\"text-align: center;\">0,5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">15<\/td>\n<td style=\"text-align: center;\">10.02.2020<\/td>\n<td style=\"text-align: center;\">12:05<\/td>\n<td>Reichertshausen<br>Bergweg<br>Dach abgedeckt<\/td>\n<td style=\"text-align: center;\">&nbsp;<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">14<\/td>\n<td style=\"text-align: center;\">10.02.2020<\/td>\n<td style=\"text-align: center;\">11:34<\/td>\n<td>Reichertshausen<br>Salmadinger Stra\u00dfe<br>Baum umgefallen<\/td>\n<td style=\"text-align: center;\">0,5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">13<\/td>\n<td style=\"text-align: center;\">10.02.2020<\/td>\n<td style=\"text-align: center;\">11:06<\/td>\n<td>Steinkirchen<br>Leitlweg<br>Baum auf Fahrbahn<\/td>\n<td style=\"text-align: center;\">1,0<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">12<\/td>\n<td style=\"text-align: center;\">10.02.2020<\/td>\n<td style=\"text-align: center;\">10:42<\/td>\n<td>Reichertshausen<br>Pfaffenhofener Str.<br>Dachziegel sichern<\/td>\n<td style=\"text-align: center;\">0,25<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">11<\/td>\n<td style=\"text-align: center;\">10.02.2020<\/td>\n<td style=\"text-align: center;\">10:08<\/td>\n<td>Steinkirchen<br>Rosenstra\u00dfe<br>Dach tw. abgedeckt<\/td>\n<td style=\"text-align: center;\">&nbsp;<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">10<\/td>\n<td style=\"text-align: center;\">10.02.2020<\/td>\n<td style=\"text-align: center;\">9:45<\/td>\n<td>Holzhof<br>Dach abgedeckt<\/td>\n<td style=\"text-align: center;\">0,5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">9<\/td>\n<td style=\"text-align: center;\">10.02.2020<\/td>\n<td style=\"text-align: center;\">9:30<\/td>\n<td>Gurn\u00f6bach<br>Baum auf Fahrbahn<\/td>\n<td style=\"text-align: center;\">0,5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">8<\/td>\n<td style=\"text-align: center;\">10.02.2020<\/td>\n<td style=\"text-align: center;\">9:20<\/td>\n<td>Kreut<br>Dach abgedeckt<\/td>\n<td style=\"text-align: center;\">0,5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">7<\/td>\n<td style=\"text-align: center;\">10.02.2020<\/td>\n<td style=\"text-align: center;\">8:49<\/td>\n<td>Reichertshausen<br>M\u00fcnchner Stra\u00dfe<br>Dach abgedeckt<\/td>\n<td style=\"text-align: center;\">0,75<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">6<\/td>\n<td style=\"text-align: center;\">10.02.2020<\/td>\n<td style=\"text-align: center;\">8:38<\/td>\n<td>Reichertshausen<br>Waldfriedhof<br>Baum in Friedhof<\/td>\n<td style=\"text-align: center;\">0,75<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">5<\/td>\n<td style=\"text-align: center;\">10.02.2020<\/td>\n<td style=\"text-align: center;\">8:09<\/td>\n<td>Kreut<br>Geb\u00e4ude sichern<\/td>\n<td style=\"text-align: center;\">0,33<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">4<\/td>\n<td style=\"text-align: center;\">10.02.2020<\/td>\n<td style=\"text-align: center;\">8:05<\/td>\n<td>Paindorf<br>Dorfstra\u00dfe<br>Gartenhaus sichern<\/td>\n<td style=\"text-align: center;\">&nbsp;<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">3<\/td>\n<td style=\"text-align: center;\">10.02.2020<\/td>\n<td style=\"text-align: center;\">7:30<\/td>\n<td>Reichertshausen<br>Riederweg<br>Baum auf Fahrbahn<\/td>\n<td style=\"text-align: center;\">0,5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">2<\/td>\n<td style=\"text-align: center;\">10.02.2020<\/td>\n<td style=\"text-align: center;\">7:12<\/td>\n<td>Oberpaindorf<br>Ringstra\u00dfe<br>Baum auf Garage<\/td>\n<td style=\"text-align: center;\">0,75<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: right;\">1<\/td>\n<td style=\"text-align: center;\">01.02.2020<\/td>\n<td style=\"text-align: center;\">17:30<\/td>\n<td>Reichertshausen<br>Ilmtalhalle<br>Parkpl\u00e4tze einweisen<\/td>\n<td style=\"text-align: center;\">2,5<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><a href=\"https:\/\/www.ff-reichertshausen.de\/cms\/einsaetze\/einsaetze-2019\/\"><img decoding=\"async\" src=\"https:\/\/www.ff-reichertshausen.de\/cms\/wp-content\/themes\/twentyten-ffrs\/images\/strahlrohr-l.gif\" alt=\"\"> Weiter zu Eins\u00e4tze 2019&#8230;<\/a><\/p>\n<p><a href=\"https:\/\/www.ff-reichertshausen.de\/cms\/?page_id=25\"><img decoding=\"async\" src=\"https:\/\/www.ff-reichertshausen.de\/cms\/wp-content\/themes\/twentyten-ffrs\/images\/strahlrohr-l.gif\" alt=\"\"> Unsere Eins\u00e4tze seit 2011<br>(Beginn unserer Einsatz-Ver\u00f6ffentlichungen im Internet &#8230;)<\/a><\/p>\n<table width=\"380\">\n<tbody>\n<tr>\n<th>&nbsp;<\/th>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><a href=\"https:\/\/www.ff-reichertshausen.de\/pdf-docs\/adac-blaulicht-martinshorn.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-147 alignright\" title=\"Wichtige Hinweise zu Blaulicht und Martinshorn ...\" src=\"https:\/\/www.ff-reichertshausen.de\/cms\/wp-content\/uploads\/2011\/01\/Blaulicht.gif\" alt=\"\" width=\"104\" height=\"120\"><\/a><\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unser Einsatz war zuletzt notwendig: Nr Datum Uhrzeit Ort und Einsatz Dauer(Std.) 32 14.12.2020 7:16 PaindorfPKW-Brand 3,00 31 07.11.2020 2:07 LettenDachstuhlbrand &#8211; Fehlalarm 0,25 30 29.10.2020 17:57 KreutVerkehrsunfall &#8211; Fehlalarm(Meldung \u00fcber e-call) 0,5 29 20.09.2020 20:57 B13 H\u00f6he SalmadingVerkehrsunfall 1,5 28 12.07.2020 15:25 GrafingBrand im Freien &#8211; Nachschau 0,75 27 05.07.2020 10:40 OberpaindorfPerson von Zug &hellip; <a href=\"https:\/\/www.ff-reichertshausen.de\/cms\/einsaetze\/einsaetze-2021\/einsaetze-2020\/\" class=\"more-link\"><span class=\"screen-reader-text\">Eins\u00e4tze 2020<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":14,"featured_media":0,"parent":3644,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3073","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.ff-reichertshausen.de\/cms\/wp-json\/wp\/v2\/pages\/3073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ff-reichertshausen.de\/cms\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ff-reichertshausen.de\/cms\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ff-reichertshausen.de\/cms\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ff-reichertshausen.de\/cms\/wp-json\/wp\/v2\/comments?post=3073"}],"version-history":[{"count":0,"href":"https:\/\/www.ff-reichertshausen.de\/cms\/wp-json\/wp\/v2\/pages\/3073\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.ff-reichertshausen.de\/cms\/wp-json\/wp\/v2\/pages\/3644"}],"wp:attachment":[{"href":"https:\/\/www.ff-reichertshausen.de\/cms\/wp-json\/wp\/v2\/media?parent=3073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}